{"id":5363,"date":"2022-08-25T23:59:00","date_gmt":"2022-08-25T21:59:00","guid":{"rendered":"http:\/\/www.the-new-listener.de\/?p=5363"},"modified":"2022-08-26T23:12:16","modified_gmt":"2022-08-26T21:12:16","slug":"der-kecke-besen-in-vollendung-remy-ballot-altomonte-orchester-hard-chor-brucknertage-st-florian","status":"publish","type":"post","link":"http:\/\/www.the-new-listener.de\/index.php\/2022\/08\/25\/der-kecke-besen-in-vollendung-remy-ballot-altomonte-orchester-hard-chor-brucknertage-st-florian\/","title":{"rendered":"Der \u201ekecke Besen\u201c in Vollendung: Ballot dirigiert Bruckner in St.\u00a0Florian"},"content":{"rendered":"\n<p><em>Auf den St.&nbsp;Florianer Brucknertagen erklangen am 19. und 20. August 2022 Anton Bruckners Symphonie Nr.&nbsp;1 (Fassung 1890) und Te Deum. R\u00e9my Ballot dirigierte das Altomonte Orchester St.&nbsp;Florian und den Hard Chor. Die Soli sangen Regina Riel (Sopran), Gerda Lischka (Alt), Markus Miesenberger (Tenor) und Michael Wagner (Bass).<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"http:\/\/www.the-new-listener.de\/wp-content\/uploads\/2022\/08\/20220819_161945-scaled.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"768\" src=\"http:\/\/www.the-new-listener.de\/wp-content\/uploads\/2022\/08\/20220819_161945-1024x768.jpg\" alt=\"\" class=\"wp-image-5366\" srcset=\"http:\/\/www.the-new-listener.de\/wp-content\/uploads\/2022\/08\/20220819_161945-1024x768.jpg 1024w, http:\/\/www.the-new-listener.de\/wp-content\/uploads\/2022\/08\/20220819_161945-300x225.jpg 300w, http:\/\/www.the-new-listener.de\/wp-content\/uploads\/2022\/08\/20220819_161945-768x576.jpg 768w, http:\/\/www.the-new-listener.de\/wp-content\/uploads\/2022\/08\/20220819_161945-1536x1152.jpg 1536w, http:\/\/www.the-new-listener.de\/wp-content\/uploads\/2022\/08\/20220819_161945-2048x1536.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption>Augustiner Chorherrenstift St. Florian, vom Literaturgarten aus gesehen. An der Wegbiegung steht ein Bruckner-Denkmal.<\/figcaption><\/figure>\n\n\n\n<p>R\u00e9my Ballot steht mittlerweile im verdienten Ruf eines Garanten erstrangiger Auff\u00fchrungen der Symphonien Anton Bruckners. Seit 2013 markieren die von ihm geleiteten Orchesterkonzerte den H\u00f6hepunkt der j\u00e4hrlich an der Wirkungs- und Begr\u00e4bnisst\u00e4tte des Meisters veranstalteten St.&nbsp;Florianer Brucknertage. Eine Symphonie nach der anderen ist dabei im Laufe der vergangenen Jahre unter Ballots Dirigat in der Basilika des Augustiner Chorherrenstifts St.&nbsp;Florian zur Auff\u00fchrung gelangt. Die Mitschnitte wurden von Gramola auf CD ver\u00f6ffentlicht. Zuletzt erschien im April 2022 die Vierte Symphonie. In Zusammenarbeit mit zwei Orchestern hat Ballot nun beinahe einen kompletten Bruckner-Zyklus vorgelegt: Die Symphonien Nr.&nbsp;2, 3, 4, 5, 7 und 9 wurden mit dem Altomonte Orchester St.&nbsp;Florian aufgenommen, Nr.&nbsp;6 und Nr.&nbsp;8 mit dem Ober\u00f6sterreichischen Jugendsinfonieorchester.<\/p>\n\n\n\n<p>Die Reihe der nummerierten Symphonien wurde am 19. und 20. August 2022 durch Auff\u00fchrungen der Ersten Symphonie vervollst\u00e4ndigt, denen sich im zweiten Teil beider Konzerte Bruckners Te Deum anschloss. Erneut dirigierte Ballot das Altomonte Orchester St.&nbsp;Florian. Im Te Deum war der Hard Chor, einstudiert von seinem Leiter Alexander Koller, zu h\u00f6ren. Die Solopartien \u00fcbernahmen Regina Riel (Sopran), Gerda Lischka (Alt), Markus Miesenberger (Tenor) und Michael Wagner (Bass). (Die Besprechung bezieht sich auf das Konzert am 19. August.)<\/p>\n\n\n\n<p>Auch im Falle der Ersten stellt sich die Frage, die sich bei der Mehrheit der Brucknerschen Symphonien stellt, n\u00e4mlich welche Fassung man zur Auff\u00fchrung ausw\u00e4hlen soll. Ballot hat diese Frage in der Vergangenheit durchaus nicht schematisch beantwortet, und weder den Erstfassungen, noch den Fassungen letzter Hand pauschal den Vorzug gegeben. Letztlich gaben immer k\u00fcnstlerische Gr\u00fcnde den Ausschlag. So dirigierte er die Zweite und Dritte in ihrer ersten, die Vierte und Achte in ihrer jeweils letzten Fassung. Auch bei der Ersten hat er sich f\u00fcr die Letztfassung entschieden, die im Gegensatz zur \u00e4lteren \u201eLinzer Fassung\u201c als \u201eWiener Fassung\u201c bezeichnet wird.<\/p>\n\n\n\n<p>Obwohl die \u201eWiener Fassung\u201c als Bruckners letztes Wort in Bezug auf seinen offiziellen symphonischen Erstling gelten muss, wurde sie doch im Konzertleben weitgehend von der \u201eLinzer Fassung\u201c verdr\u00e4ngt, nachdem diese 1935 von Robert Haas im Rahmen der alten Gesamtausgabe erstmals herausgegeben worden war. Zahlreiche Autoren gelangten seitdem zu der Ansicht, in dieser Version den \u201ekecken Besen\u201c \u2013 wie der Komponist sein Werk selbst zu nennen pflegte \u2013 in urspr\u00fcnglicher, unverstellter Gestalt vor sich zu haben. Die sp\u00e4te Bearbeitung von 1890, die immerhin ein ganzes Vierteljahrhundert nach Vollendung der Erstfassung erfolgte, habe dagegen den Charakter des Werkes verf\u00e4lscht, ihm ein unpassendes neues Gewand \u00fcbergest\u00fclpt. Dass Bruckner selbst dieser Ansicht nicht war, liegt auf der Hand: Warum h\u00e4tte er eine Neufassung \u00fcberhaupt in Erw\u00e4gung gezogen, wenn er nicht meinte, damit sein Werk zu verbessern? Er hatte seit Vollendung der Erstfassung eine lange Entwicklung durchgemacht, neue Erfahrungen gesammelt, und wollte vor diesem Hintergrund die Erste f\u00fcr die anstehende Drucklegung gleichsam auf den neuesten Stand seines K\u00f6nnens bringen. Instrumentatorisch schlug sich dies vor allem in einer st\u00e4rkeren Beteiligung der Blechbl\u00e4ser an der thematischen Arbeit nieder, formal in zahlreichen kleineren Revisionen, die auf Begradigung der Periodenstruktur abzielten. Auch in den Tempi nahm Bruckner Ver\u00e4nderungen vor, wobei im Finale die Tendenz zur Verlangsamung des Ablaufs nicht zu \u00fcbersehen ist: Der Seitensatz, zuvor vom Haupttempo (\u201ebewegt, feurig\u201c) nicht abgegrenzt, soll nun \u201elangsamer\u201c gespielt werden, der von diesem dominierte Abschnitt der Durchf\u00fchrung erst \u201elangsam\u201c, dann \u201esehr langsam\u201c; in der Coda schlie\u00dflich weist Bruckner an, das Haupttempo zuerst auf \u201elangsam\u201c zu reduzieren und dann die letzten Takte des Satzes \u201esehr breit\u201c zu spielen. Deutlich zeigt sich anhand dieser Tempodramaturgie die Angleichung an Finals\u00e4tze sp\u00e4terer Symphonien.<\/p>\n\n\n\n<p>Ist die \u201eWiener Fassung\u201c also die Verzeichnung eines Meisterwerks durch den eigenen Sch\u00f6pfer? Anhand gewisser Einspielungen m\u00f6chte man das wohl glauben. Vielleicht hat Bruckners Charakterisierung der Symphonie als \u201ekecken Besen\u201c bewirkt, dass sich eine Art Tradition herausgebildet hat, das Werk besonders \u201ekeck\u201c zu spielen, worunter man offenbar rasche Tempi und einen derb zupackenden, \u201erustikalen\u201c Vortrag versteht. Dazu passen in der Tat die 1890 im Finale angebrachten neuen Tempovorschriften nicht gut. Will man die Symphonie flink und raubeinig musizieren, so wirken sie hemmend und bremsend und letztlich aufgesetzt. Die Frage ist freilich, ob man die Erste zwangsl\u00e4ufig so spielen muss. Nun ist dieses Werk die am wenigsten von der sakralen Sph\u00e4re ber\u00fchrte unter allen vom Komponisten als g\u00fcltig betrachteten Symphonien \u2013 wenn man so will: die weltlichste. Es gibt keine Zitate aus eigenen Kirchenmusikwerken (wie in der Zweiten, Siebten, Neunten), und choralartige Stellen sind h\u00f6chstens andeutungsweise vorhanden. Dennoch teilt die Erste mit ihren j\u00fcngeren Geschwistern den typisch Brucknerschen Zug ins Expansive. Julian Horton hat diesen Umstand in einem Referat im Rahmen des w\u00e4hrend der Brucknertage in St.&nbsp;Florian abgehaltenen Symposiums \u201eBruckner-Dimensionen\u201c anschaulich dargelegt: Bereits in der Ersten Symphonie umgeht Bruckner das traditionelle Kadenzieren bei der Aufstellung der Themen und treibt die Musik stattdessen kontinuierlich weiter. Die f\u00fcr ihn charakteristische Formung der Musik durch gro\u00dfangelegte Steigerungswellen findet sich hier schon in voller Meisterschaft ausgef\u00fchrt. Dass zwischen der Ersten und den folgenden Symphonien allen Unterschieden zum Trotz eine starke innere Verbindung besteht, l\u00e4sst sich nicht leugnen. Diese Verbindung wollte Bruckner in der \u201eWiener Fassung\u201c der Ersten anscheinend unterstreichen.<\/p>\n\n\n\n<p>R\u00e9my Ballot hat die \u201eWiener Fassung\u201c offensichtlich nicht als des \u201ekecken Besens\u201c Z\u00e4hmung verstanden, sondern als die letztg\u00fcltige Ausformung eines fr\u00fchen Meisterwerks, in dem wesentliche Gestaltungsmittel der Brucknerschen Kunst bereits un\u00fcberh\u00f6rbar zum Einsatz kommen. Konsequent ist er diesen Ph\u00e4nomenen auf den Grund gegangen und hat Bruckners Streben ins Weite und Hohe, den unaufh\u00f6rlichen Drang der Musik nach Fortentwicklung und Intensivierung in einer Art und Weise umgesetzt, wie sie der Verfasser dieser Zeilen noch in keiner anderen Auff\u00fchrung dieses Werkes erlebt hat. Die ganze Darbietung wurde getragen von einem untr\u00fcglichen Sinn f\u00fcr den Aufbau des Ganzen. Die Sequenzen waren nicht einfach nur Transpositionen von Motiven auf verschiedene Stufen: Sie lie\u00dfen wahrhaft sp\u00fcren, wie st\u00e4ndig Neues hinzukam, wie die Motive gleichsam neue Erfahrungen machen, einen Entwicklungsprozess durchlaufen. Entsprechend bauten sich die gr\u00f6\u00dferen Abschnitte der Form auf. Immer behielt der Dirigent, den man einen Meister des \u201eFernh\u00f6rens\u201c nennen muss, im Blick, welche Richtung die Musik gerade nimmt. So h\u00f6rte man denn hier auch weniger ein erstes Thema, dann ein zweites, drittes, viertes, die Durchf\u00fchrung usw., man h\u00f6rte vier ganze S\u00e4tze, vier weitgespannte Entwicklungsb\u00f6gen, deren einzelne Teile ganz nat\u00fcrlich auseinander hervorgingen und so untrennbar miteinander verbunden waren wie die Phrasen einer schlichten Liedmelodie. Wie sagte einst Donald Tovey: \u201eForm is melody written large.\u201c In St.&nbsp;Florian konnte man das erleben!<\/p>\n\n\n\n<p>Der lange Nachhall der Stiftsbasilika verbietet \u00fcberhastete Tempi nahezu von selbst. Auf die Bedingungen des Raumes eingehend, w\u00e4hlte Ballot breite Zeitma\u00dfe, sodass die Symphonie rund eine Stunde dauerte. Der kluge Umgang mit dem Nachhall sorgte daf\u00fcr, dass dieser als fester Bestandteil des musikalischen Konzepts sp\u00fcrbar wurde. Bruckners Generalpausen gerieten zu Momenten des Ausatmens und der inneren Sammlung, was sich besonders deutlich an jenen zwei Stellen im Finale zeigte, an denen die Musik nach einem Fortissimo abrupt verstummt (beim zweiten Mal unter Zur\u00fccklassung eines abklingenden Paukenwirbels): Der geballte Klang l\u00f6ste sich w\u00e4hrend seiner mehrere Sekunden langen Wanderung durch das Kirchenschiff, dann setzte im Moment seines endg\u00fcltigen Verstummens, den Faden aufnehmend, die Musik wieder ein. Wer m\u00f6chte da noch daran zweifeln, dass Bruckner die St.&nbsp;Florianer Akustik derma\u00dfen in Mark und Bein \u00fcbergegangen ist, dass er sie beim Komponieren stets mitgedacht hat? In diesem Raum lie\u00df Ballot das Adagio mit der Stille Zwiesprache halten, bevor es sich in langen Atemz\u00fcgen entfalten durfte, und machte zum Schluss Ernst mit den Tempi, die Bruckner 1890 in die Coda des Finales eintrug. Die Intensit\u00e4t, mit der sich die Musik w\u00e4hrend der letzten Takte in immer breiter werdendem Zeitma\u00df auft\u00fcrmte, hielt das Publikum noch lange nach dem Verklingen des letzten Akkordes gebannt, sodass der Applaus erst sp\u00e4t einsetzte, daf\u00fcr aber umso st\u00fcrmischer.<\/p>\n\n\n\n<p>Im Te Deum stand der Dirigent vor der Herausforderung, den nur etwa 60 Mitglieder z\u00e4hlenden Chor nicht vom Orchester zudecken zu lassen. Hatte Ballot seine Instrumentalisten in der Symphonie zuletzt bis zur \u00e4u\u00dfersten Prachtentfaltung motiviert, so galt es nun, sie zur Zur\u00fcckhaltung anzuhalten und gleichzeitig Bruckners Orchestersatz mit der n\u00f6tigen Differenziertheit zur Geltung zu bringen. Auch diese Aufgabe wurde trefflich gel\u00f6st. Keine wichtige Orchesterstimme ging unter, doch blieben die Instrumente stets nur Begleitung und St\u00fctze des Chores und der Vokalsolisten. F\u00fcr die Violinsoli im zweiten und vierten Teil machte sich der Dirigent wieder die besonderen Gegebenheiten des Raumes nutzbar und lie\u00df die Soloviolinistin von der Kanzel aus spielen. Es war dies nicht nur eine musikalisch \u00fcberzeugende L\u00f6sung, sondern harmonierte auch mit der bildhauerischen Ausgestaltung des Chorraums, sieht man doch \u00fcber dem Chorgest\u00fchl eine Schar Engel musizieren, u.&nbsp;a. auf Geigen. Gegen Ende der Auff\u00fchrung schaffte es Ballot, seinem Chor zus\u00e4tzliche Kr\u00e4fte zu entlocken, sodass in den letzten Takten eine nochmalige Steigerung gelang. Das Solistenquartett hatte allerdings den Punkt seiner gr\u00f6\u00dften Ausgewogenheit am Ende der Generalprobe Tags zuvor erreicht. Hatte man im Verlauf derselben erleben k\u00f6nnen, wie Altistin Gerda Lischka nach anf\u00e4nglich zu starker Zur\u00fcckhaltung immer deutlicher zwischen Sopranistin Regina Riel und Tenor Markus Miesenberger als Mittelstimme durchklang, so wirkte Regina Riel im Konzert etwas weniger pr\u00e4sent als in der Probe.<\/p>\n\n\n\n<p>Wer bei den Proben dabei war, merkte, wie wichtig Ballot bei seiner Arbeit der Kontakt zu den Musikern ist. Er versteht es, in jeder Situation den betreffenden Orchestergruppen ihre Bedeutung innerhalb des Ganzen zu vermitteln, sie zueinander in Relation zu setzen und gegeneinander abzustufen. Die Zeichengebung beschr\u00e4nkt er dabei auf das Wesentliche, was nicht hei\u00dft, dass er nicht, wenn es die Musik erfordert, zu markanten Gesten f\u00e4hig w\u00e4re. Bringt er eine solche ins Spiel, dann meint er damit auch etwas Bestimmes. Wichtige Motive und Phrasen hebt er durch st\u00e4rkeres Herausstreichen der entsprechenden Taktteile hervor und schafft damit jenes leichte, fl\u00fcssige Rubato, das sich reizvoll belebend \u00fcber den sp\u00fcrbar bleibenden Grundpuls der Musik legt. Man merkt, hier ist nicht nur ein handwerklich \u00e4u\u00dferst versierter Kapellmeister am Werk, sondern auch ein Musiker, der die von ihm dirigierte Musik intensiv durchlebt und das Orchester entsprechend zu animieren wei\u00df.<\/p>\n\n\n\n<p>Ballots St.&nbsp;Florianer Bruckner-Zyklus ist mit diesem Konzert \u00fcbrigens noch nicht abgeschlossen. Das Programmheft der Brucknertage vermeldet Vorfreude auf die annullierte d-Moll-Symphonie (die \u201eNullte\u201c) und den 146.&nbsp;Psalm, die im August 2023 in der Basilika erklingen sollen. Ja, darauf darf man sich in der Tat freuen, ebenso auf die CD-Ver\u00f6ffentlichung des diesj\u00e4hrigen Konzerts!<\/p>\n\n\n\n<p><strong>[Norbert Florian Schuck, August 2022]<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Auf den St.&nbsp;Florianer Brucknertagen erklangen am 19. und 20. August 2022 Anton Bruckners Symphonie Nr.&nbsp;1 (Fassung 1890) und Te Deum. R\u00e9my Ballot dirigierte das Altomonte Orchester St.&nbsp;Florian und den Hard Chor. Die Soli sangen Regina Riel (Sopran), Gerda Lischka (Alt), Markus Miesenberger (Tenor) und Michael Wagner (Bass). R\u00e9my Ballot steht mittlerweile im verdienten Ruf eines &hellip; <a href=\"http:\/\/www.the-new-listener.de\/index.php\/2022\/08\/25\/der-kecke-besen-in-vollendung-remy-ballot-altomonte-orchester-hard-chor-brucknertage-st-florian\/\" class=\"more-link\"><span class=\"screen-reader-text\">Der \u201ekecke Besen\u201c in Vollendung: Ballot dirigiert Bruckner in St.\u00a0Florian<\/span> weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[4439,4434,1941,4436,4433,4443,4440,4441,4435,4437,4442,4438],"_links":{"self":[{"href":"http:\/\/www.the-new-listener.de\/index.php\/wp-json\/wp\/v2\/posts\/5363"}],"collection":[{"href":"http:\/\/www.the-new-listener.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.the-new-listener.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.the-new-listener.de\/index.php\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"http:\/\/www.the-new-listener.de\/index.php\/wp-json\/wp\/v2\/comments?post=5363"}],"version-history":[{"count":5,"href":"http:\/\/www.the-new-listener.de\/index.php\/wp-json\/wp\/v2\/posts\/5363\/revisions"}],"predecessor-version":[{"id":5375,"href":"http:\/\/www.the-new-listener.de\/index.php\/wp-json\/wp\/v2\/posts\/5363\/revisions\/5375"}],"wp:attachment":[{"href":"http:\/\/www.the-new-listener.de\/index.php\/wp-json\/wp\/v2\/media?parent=5363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.the-new-listener.de\/index.php\/wp-json\/wp\/v2\/categories?post=5363"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.the-new-listener.de\/index.php\/wp-json\/wp\/v2\/tags?post=5363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}