{"id":5741,"date":"2023-06-10T03:34:55","date_gmt":"2023-06-10T01:34:55","guid":{"rendered":"http:\/\/www.the-new-listener.de\/?p=5741"},"modified":"2023-06-10T03:35:00","modified_gmt":"2023-06-10T01:35:00","slug":"rezensionen-im-vergleich-1-erste-gesamtaufnahme-der-orgelmusik-felix-woyrschs","status":"publish","type":"post","link":"http:\/\/www.the-new-listener.de\/index.php\/2023\/06\/10\/rezensionen-im-vergleich-1-erste-gesamtaufnahme-der-orgelmusik-felix-woyrschs\/","title":{"rendered":"[Rezensionen im Vergleich\u00a01] Erste Gesamtaufnahme der Orgelmusik Felix Woyrschs"},"content":{"rendered":"\n<p>Toccata Classics TOCC 0120; EAN: 5 060113 441201<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><a href=\"http:\/\/www.the-new-listener.de\/wp-content\/uploads\/2023\/06\/Woyrsch-Orgelwerke-Forsbach-Toccata.jpg\"><img loading=\"lazy\" src=\"http:\/\/www.the-new-listener.de\/wp-content\/uploads\/2023\/06\/Woyrsch-Orgelwerke-Forsbach-Toccata-1024x1024.jpg\" alt=\"\" class=\"wp-image-5742\" width=\"510\" height=\"510\" srcset=\"http:\/\/www.the-new-listener.de\/wp-content\/uploads\/2023\/06\/Woyrsch-Orgelwerke-Forsbach-Toccata-1024x1024.jpg 1024w, http:\/\/www.the-new-listener.de\/wp-content\/uploads\/2023\/06\/Woyrsch-Orgelwerke-Forsbach-Toccata-300x300.jpg 300w, http:\/\/www.the-new-listener.de\/wp-content\/uploads\/2023\/06\/Woyrsch-Orgelwerke-Forsbach-Toccata-150x150.jpg 150w, http:\/\/www.the-new-listener.de\/wp-content\/uploads\/2023\/06\/Woyrsch-Orgelwerke-Forsbach-Toccata-768x768.jpg 768w, http:\/\/www.the-new-listener.de\/wp-content\/uploads\/2023\/06\/Woyrsch-Orgelwerke-Forsbach-Toccata.jpg 1500w\" sizes=\"(max-width: 510px) 100vw, 510px\" \/><\/a><\/figure>\n\n\n\n<p><em>F\u00fcr Toccata Classics hat Ruth Forsbach auf der Wilhelm-Sauer-Orgel der reformierten Kirche in Wuppertal-Ronsdorf s\u00e4mtliche Orgelkompositionen von Felix Woyrsch eingespielt.<\/em><\/p>\n\n\n\n<p>Der 1860 geborene Felix Woyrsch, von 1914 bis 1931 erster (und einziger) St\u00e4dtischer Musikdirektor im damals noch nicht zu Hamburg geh\u00f6renden Altona, wurde vor allem durch seine Oratorien und Symphonien bekannt. Auf beiden Gebieten kann er als der bedeutendste norddeutsche Komponist aus der Generation nach Johannes Brahms gelten. Angesichts der \u00fcberregionalen Erfolge seiner Chor- und Orchesterwerke (das Passionsoratorium und das Mysterium <em>Totentanz<\/em> drangen bis nach Gro\u00dfbritannien und in die USA vor), sowie seiner Leistungen als Chorleiter und Orchesterdirigent, der erstmals in Altona regelm\u00e4\u00dfige Symphoniekonzerte veranstaltete, wird mitunter vergessen, dass Woyrsch immerhin drei Jahrzehnte lang, von 1895 bis 1925, einer regelm\u00e4\u00dfigen Organistent\u00e4tigkeit nachging. Freilich verlief dieser Teil seines Wirkens wenig aufsehenerregend und beschr\u00e4nkte sich auf die Begleitung von Gottesdiensten in Altonaer Kirchen. Auch der Umstand, dass Woyrsch nur relativ wenige Kompositionen f\u00fcr die Orgel schrieb, mag dazu beigetragen haben, dass sein Name meist nicht in erster Linie mit der \u201eK\u00f6nigin der Instrumente\u201c in Verbindung gebracht wird. Keineswegs sollte man daraus jedoch den Schluss ziehen, es handle sich bei den Orgelst\u00fccken des Komponisten um qualitativ hinter seinen symphonischen und oratorischen Werken zur\u00fcckstehende Musik.<\/p>\n\n\n\n<p>Woyrschs gesamtes Orgelschaffen umfasst insgesamt zw\u00f6lf Einzelst\u00fccke, die sich auf drei Opuszahlen verteilen und allesamt in seiner mittleren Schaffensperiode entstanden. Am Beginn steht das 1895 komponierte <em>Festpraeludium \u00fcber den Choral \u201eNun danket alle Gott\u201c<\/em> op.&nbsp;43. Die \u00fcbrigen Kompositionen wurden 1921 ver\u00f6ffentlicht. Es handelt sich um die zwischen 1909 und 1918 entstandenen <em>Zehn Choralvorspiele<\/em> op.&nbsp;59 und die <em>Passacaglia \u00fcber das \u201eDies Irae\u201c<\/em> op.&nbsp;62. So wenig umfangreich dieser Werkbestand rein zahlenm\u00e4\u00dfig sein mag, bieten die St\u00fccke doch eine gute Einf\u00fchrung in Woyrschs Kompositionsstil. Man lernt aus ihnen einen K\u00fcnstler kennen, dem der Kontrapunkt nicht blo\u00df Handwerksmittel, sondern Tr\u00e4ger poetischer Ideen ist, einen wahren Gro\u00dfmeister der Tonalit\u00e4t, der seine Musik souver\u00e4n durch Nebenharmonien und Zwischenstufen f\u00fchren kann, ohne das Zentrum aus dem Blick zu verlieren, und nicht zuletzt einen vielseitigen Tondichter, der der Orgel ein breites Spektrum musikalischer Charaktere abzugewinnen wei\u00df. Die Stimmung verschiebt sich, h\u00f6rt man die St\u00fccke in der Reihenfolge ihrer Nummerierung, allerdings immer mehr hin zum D\u00fcsteren, was offensichtlich mit der zeitlichen N\u00e4he der meisten Choralvorspiele und der Passacaglia zum Ersten Weltkrieg zusammenh\u00e4ngt. Wie Andreas Dreibrodt und Andreas Willscher, zwei der besten Kenner von Woyrschs Schaffen, in ihrem sehr informativen Begleittext schreiben, passt auch das Festpraeludium op.&nbsp;43, obwohl viel fr\u00fcher und ohne jeden milit\u00e4rischen Bezug entstanden, durchaus in die Kriegszeit, liegt ihm doch jene Melodie zugrunde, die die Soldaten Friedrichs des Gro\u00dfen einst als \u201eChoral von Leuthen\u201c anstimmten, \u2013 und in Erinnerung daran tausende Deutsche zu Beginn des Krieges vor dem Berliner Schloss. Man beginnt die Reise durch Woyrschs Orgelwerk also in festlicher Aufbruchsstimmung, die jedoch in den Choralvorspielen op.&nbsp;59 ziemlich bald zur\u00fcckgenommen wird. Die ersten drei sind Weihnachtsst\u00fccke (<em>Nun komm der Heiden Heiland<\/em>, <em>Es ist ein Ros entsprungen<\/em>, <em>Vom Himmel hoch, da komm ich her<\/em>), dann folgen Werke der Klage und Trauer (<em>Ach Gott, vom Himmel sieh darein<\/em>, <em>O Haupt voll Blut und Wunden<\/em>, <em>O Traurigkeit, o Herzeleid<\/em>), und ein gleichfalls dunkel get\u00f6ntes Vorspiel \u00fcber <em>Was mein Gott will, das g&#8217;scheh allzeit<\/em>. Wenn mit Nr.&nbsp;8 doch noch einmal ein <em>Festpraeludium<\/em> auftaucht, dann eines \u00fcber <em>Valet will ich dir geben<\/em> [du arge, falsche Welt]. Nr.&nbsp;9, <em>Nun ruhen alle W\u00e4lder<\/em>, ist als Trio mit kanonischen Oberstimmen komponiert, die permanent andere Harmonien ansteuern als von der im Bass liegenden Choralmelodie eigentlich impliziert \u2013 in den \u201eruhigen\u201c W\u00e4ldern rauscht es unheimlich. Schlie\u00dflich spricht Woyrsch offen aus, was viele \u201eim Kriegsjahr 1918\u201c (so f\u00fcgt er ausdr\u00fccklich dem Titel hinzu) dachten, und setzt ans Ende der Sammlung ein Vorspiel \u00fcber <em>Verleih uns Frieden gn\u00e4diglich<\/em>. Die vermutlich noch im oder kurz nach dem Krieg entstandene Passacaglia op.&nbsp;62 entpuppt sich als Totentanz in bester Lisztscher Tradition (wenngleich man rein stilistisch eher Bach und Brahms als Vorbilder ausmachen mag) \u2013 ein passender Abschluss dieses Orgelschaffens, das, ohne dass der Komponist dies zu Beginn intendiert haben kann, ihm gleichsam unter der Hand zu einem bemerkenswert in sich geschlossenen Kriegszyklus geworden ist.<\/p>\n\n\n\n<p>Obwohl alle Werke auf vorhandene Themen komponiert sind, legen sie von Woyrsch nicht nur als Kontrapunktiker und Harmoniker ein h\u00f6chst g\u00fcnstiges Zeugnis ab, sondern auch als Melodiker, der sich trefflich darauf versteht, aus dem Material der Choralmelodien neue Themen zu bilden (op.&nbsp;43, op.&nbsp;59\/8) bzw. freie Begleitmotive zu ihnen zu erfinden (op.&nbsp;59\/5, op.&nbsp;59\/10). Freilich verschm\u00e4ht er streng aus der Melodie abgeleitete Vorimitationen keineswegs, wie op.&nbsp;59\/4 und op.&nbsp;59\/5 zeigen. In der Passacaglia feiert das zum Dies-Irae-Thema mit unersch\u00f6pflichem Einfallsreichtum stets neue Gegenstimmen erfindende melodische Talent des Komponisten Triumphe von Variation zu Variation. So schmal der Werkbestand Woyrschs f\u00fcr die Orgel sein mag, so qualitativ hochwertig ist er auch. Man kann jedes einzelne dieser Orgelst\u00fccke bedenkenlos neben Werken von Bach, Brahms oder Reger auff\u00fchren.<\/p>\n\n\n\n<p>Der D\u00fcsseldorfer Organistin Ruth Forsbach, seit 1999 Kirchenmusikdirektorin der Evangelischen Kirche im Rheinland, ist nun die erste Gesamteinspielung des Woyrschschen Orgelschaffens zu verdanken, die, mit Ausnahme von op.&nbsp;59\/5, zugleich die Ersteinspielung aller St\u00fccke auf CD darstellt. Wie bereits erw\u00e4hnt, ist das Album, wie bei Ver\u00f6ffentlichungen von Toccata Classics h\u00e4ufig, mit einem vorz\u00fcglichen Einf\u00fchrungstext ausgestattet. Ich w\u00fcnschte, ich k\u00f6nnte gleiches von der Auff\u00fchrung der Werke selbst sagen!<\/p>\n\n\n\n<p>Gewiss hat Ruth Forsbach mit der 1908 erbauten Sauer-Orgel der reformierten Kirche in Wuppertal-Ronsdorf ein zur Wiedergabe der Kompositionen Felix Woyrschs bestens geeignetes Instrument ausgew\u00e4hlt, auch registriert sie ansprechend. Dennoch lassen ihre Darbietungen manche W\u00fcnsche offen, sodass man hier keineswegs von einer idealen Aufnahme sprechen kann. Es f\u00e4ngt mit der wenig kantablen Ausf\u00fchrung der Choralmelodien selbst an. Gerade Choralvorspiele sollten doch daran erinnern, dass Telemanns Spruch vom Singen als \u201eFundament der Musik in allen Dingen\u201c auch f\u00fcr das Musizieren auf der Orgel gilt! Gerade weil sie zu den Instrumenten z\u00e4hlt, deren Tonerzeugung derjenigen der menschlichen Stimme eher un\u00e4hnlich ist, ist ein m\u00f6glichst gesanglicher Vortrag, mit viel Sinn f\u00fcr weite melodische Entwicklungen, wichtig. Forsbachs Spiel wirkt dagegen oft zu zaghaft. Sie spielt gleichsam \u201eauf Sicht\u201c, von Takt zu Takt, sodass sich kaum einmal der Eindruck ausgedehnterer Formzusammenh\u00e4nge einstellt. Durch Rubati scheint sie die Musik beleben zu wollen, doch klingen diese seltsam ungelenk, da sie regelm\u00e4\u00dfig quer zum jeweiligen harmonischen Gef\u00e4lle stehen. Man fragt sich: Wo bleibt das \u201efernh\u00f6ren\u201c, die Ausrichtung des Vortrags auf die kommenden musikalischen Ereignisse?<\/p>\n\n\n\n<p>Im Vorspiel \u00fcber <em>Vom Himmel hoch<\/em> (op.&nbsp;59\/3) z.&nbsp;B. stehen die einzelnen Glieder der rhythmisch markanten Einleitung zu sehr f\u00fcr sich sich und finden nicht zu einer l\u00e4ngeren Periode zusammen. Was t\u00e4nzerisch beschwingt h\u00e4tte klingen k\u00f6nnen (und, wie ich meine, m\u00fcssen), wirkt ruppig und kurzatmig. Nach Einsetzen der Choralmelodie verlangsamt Forsbach bei 0:23 merklich das Tempo, wobei der Eindruck entsteht, als w\u00e4re sie nachtr\u00e4glich auf den Gedanken gekommen, zu rasch angefangen zu haben. Bei 4:02 im op.&nbsp;43 l\u00e4sst sie die sich rasch bewegende Oberstimme stets kurz auf den in ihre Haltepunkte hineinklingenden Akkord der Unterstimmen warten, was der Stelle den Schwung nimmt. Wenn im Folgenden der Choral einsetzt, l\u00e4sst sie ihn bei den Luftpausen abrupt abrei\u00dfen und spielt die raschen Figuren zwischen den Choralzeilen rhythmisch verwaschen. \u00c4hnliches passiert in der ersten Variation der Passacaglia. Die Einleitung von op.&nbsp;59\/7 wird verschleppt, wie generell bei Kadenzen und Halbschl\u00fcssen regelm\u00e4\u00dfig Ritardandi zu h\u00f6ren sind, die weder die Stimmung intensivieren noch formgliedernde Folgerichtigkeit ausstrahlen, sondern lediglich die Musik schwerf\u00e4llig erscheinen zu lassen. Als Beispiel m\u00f6ge die Kadenz in op.&nbsp;59\/5 ab 5:15 dienen. \u00dcber diese Takte, besonders die von Pausen durchsetzten ab 5:29 erstreckt sich schlicht kein Spannungsbogen, der die Wiederkehr des Anfangs als Ziel erwarten l\u00e4sst. Das harmonisch und kontrapunktisch h\u00f6chst interessante Trio <em>Nun ruhen alle W\u00e4lder<\/em> ger\u00e4t zu einem trockenen Notenreferat. Welch ein Spiel best\u00e4ndiger gegenseitiger Anziehung und Absto\u00dfung der innig ineinander verschlungenen Kanonstimmen h\u00e4tte hier geboten werden k\u00f6nnen!<\/p>\n\n\n\n<p>Kurzum: Dieses gewiss gut gemeinte Album sollte ein Ansporn sein, Woyrschs exzellente Orgelmusik in Wiedergaben auf CD festzuhalten, die ihrer kompositorischen Qualit\u00e4t besser entsprechen. Wer eine echte Referenzaufnahme dieser Werke w\u00fcnscht, wird sich also weiterhin in Geduld \u00fcben m\u00fcssen.<\/p>\n\n\n\n<p><strong>[Norbert Florian Schuck, Juni 2023]<\/strong><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Toccata Classics TOCC 0120; EAN: 5 060113 441201 F\u00fcr Toccata Classics hat Ruth Forsbach auf der Wilhelm-Sauer-Orgel der reformierten Kirche in Wuppertal-Ronsdorf s\u00e4mtliche Orgelkompositionen von Felix Woyrsch eingespielt. Der 1860 geborene Felix Woyrsch, von 1914 bis 1931 erster (und einziger) St\u00e4dtischer Musikdirektor im damals noch nicht zu Hamburg geh\u00f6renden Altona, wurde vor allem durch seine &hellip; <a href=\"http:\/\/www.the-new-listener.de\/index.php\/2023\/06\/10\/rezensionen-im-vergleich-1-erste-gesamtaufnahme-der-orgelmusik-felix-woyrschs\/\" class=\"more-link\"><span class=\"screen-reader-text\">[Rezensionen im Vergleich\u00a01] Erste Gesamtaufnahme der Orgelmusik Felix Woyrschs<\/span> weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":18,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[13],"tags":[4132,4657,277],"_links":{"self":[{"href":"http:\/\/www.the-new-listener.de\/index.php\/wp-json\/wp\/v2\/posts\/5741"}],"collection":[{"href":"http:\/\/www.the-new-listener.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.the-new-listener.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.the-new-listener.de\/index.php\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"http:\/\/www.the-new-listener.de\/index.php\/wp-json\/wp\/v2\/comments?post=5741"}],"version-history":[{"count":1,"href":"http:\/\/www.the-new-listener.de\/index.php\/wp-json\/wp\/v2\/posts\/5741\/revisions"}],"predecessor-version":[{"id":5743,"href":"http:\/\/www.the-new-listener.de\/index.php\/wp-json\/wp\/v2\/posts\/5741\/revisions\/5743"}],"wp:attachment":[{"href":"http:\/\/www.the-new-listener.de\/index.php\/wp-json\/wp\/v2\/media?parent=5741"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.the-new-listener.de\/index.php\/wp-json\/wp\/v2\/categories?post=5741"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.the-new-listener.de\/index.php\/wp-json\/wp\/v2\/tags?post=5741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}