{"id":160,"count":2,"description":"","link":"http:\/\/www.the-new-listener.de\/index.php\/tag\/sergei-sergejewitsch-prokofjew\/","name":"Sergei Sergejewitsch Prokofjew","slug":"sergei-sergejewitsch-prokofjew","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/www.the-new-listener.de\/index.php\/wp-json\/wp\/v2\/tags\/160"}],"collection":[{"href":"http:\/\/www.the-new-listener.de\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/www.the-new-listener.de\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/www.the-new-listener.de\/index.php\/wp-json\/wp\/v2\/posts?tags=160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}