{"id":4930,"count":1,"description":"","link":"http:\/\/www.the-new-listener.de\/index.php\/tag\/dietrich-henschel\/","name":"Dietrich Henschel","slug":"dietrich-henschel","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/www.the-new-listener.de\/index.php\/wp-json\/wp\/v2\/tags\/4930"}],"collection":[{"href":"http:\/\/www.the-new-listener.de\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/www.the-new-listener.de\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/www.the-new-listener.de\/index.php\/wp-json\/wp\/v2\/posts?tags=4930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}